{"id":3686,"date":"2026-06-20T22:42:10","date_gmt":"2026-06-20T22:42:10","guid":{"rendered":"https:\/\/staging.volunteeringsolutions.com\/cost-2\/"},"modified":"2026-06-22T11:33:54","modified_gmt":"2026-06-22T11:33:54","slug":"cost","status":"publish","type":"page","link":"https:\/\/www.volunteeringsolutions.com\/de\/cost\/","title":{"rendered":"Programmkosten f\u00fcr Freiwilligenl\u00f6sungen"},"content":{"rendered":"<p>Seit 2006 erm\u00f6glicht Volunteering Solutions \u00fcber 21.000 Freiwilligen aus aller Welt gro\u00dfartige Freiwilligenerfahrungen. Mit einer Vielzahl an <a href=\"https:\/\/www.volunteeringsolutions.com\/de\/volunteer-abroad\">Programmen<\/a> ab nur 200 US-Dollar finden Sie garantiert das passende Angebot. Nachfolgend finden Sie die Kosten f\u00fcr alle L\u00e4nder und Programme, die wir anbieten. Reisen Sie in einer Gruppe oder mit Freunden? Fragen Sie uns gerne nach einem Gruppenrabatt.<\/p>\n<p> <span style=\"color:inherit;font-family:inherit;font-size:18px\">Die Programmkosten umfassen Folgendes:<\/span><\/p>\n<ul class=\"list-global\">\n<li> 24-Stunden-Hilfe und Unterst\u00fctzung durch das VS-Team<\/li>\n<li> Ausf\u00fchrliche Informationen vor der Abreise<\/li>\n<li> Projektplatzierung<\/li>\n<li> Flughafentransfer<\/li>\n<li> Orientierung<\/li>\n<li> Verpflegung (wird in den meisten Projekten bereitgestellt)<\/li>\n<li> Unterkunft<\/li>\n<li> Personalisierte \u201eMein Konto\u201c-Seite<\/li>\n<li> Teilnahme-\/Wettbewerbszertifikat (auf Anfrage)<\/li>\n<\/ul>\n<div class=\"alert alert-warning\"> *Bitte besuchen Sie die jeweilige Programmseite, um die im Preis enthaltenen Leistungen einzusehen.<\/div>\n","protected":false},"excerpt":{"rendered":"<p>Seit 2006 erm\u00f6glicht Volunteering Solutions \u00fcber 21.000 Freiwilligen aus aller Welt gro\u00dfartige Freiwilligenerfahrungen. Mit einer Vielzahl an Programmen ab nur 200 US-Dollar finden Sie garantiert das passende Angebot. Nachfolgend finden Sie die Kosten f\u00fcr alle L\u00e4nder und Programme, die wir anbieten. Reisen Sie in einer Gruppe oder mit Freunden? Fragen Sie uns gerne nach einem [&hellip;]<\/p>\n","protected":false},"author":0,"featured_media":6643,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"footnotes":""},"class_list":["post-3686","page","type-page","status-publish","has-post-thumbnail","hentry"],"acf":[],"_hostinger_reach_plugin_has_subscription_block":false,"_hostinger_reach_plugin_is_elementor":false,"_links":{"self":[{"href":"https:\/\/www.volunteeringsolutions.com\/de\/wp-json\/wp\/v2\/pages\/3686","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.volunteeringsolutions.com\/de\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/www.volunteeringsolutions.com\/de\/wp-json\/wp\/v2\/types\/page"}],"replies":[{"embeddable":true,"href":"https:\/\/www.volunteeringsolutions.com\/de\/wp-json\/wp\/v2\/comments?post=3686"}],"version-history":[{"count":2,"href":"https:\/\/www.volunteeringsolutions.com\/de\/wp-json\/wp\/v2\/pages\/3686\/revisions"}],"predecessor-version":[{"id":12248,"href":"https:\/\/www.volunteeringsolutions.com\/de\/wp-json\/wp\/v2\/pages\/3686\/revisions\/12248"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.volunteeringsolutions.com\/de\/wp-json\/wp\/v2\/media\/6643"}],"wp:attachment":[{"href":"https:\/\/www.volunteeringsolutions.com\/de\/wp-json\/wp\/v2\/media?parent=3686"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}